{"id":7496,"count":19,"description":"Selling marijuana seeds. Here you can buy great original and medicinal marijuana seeds. We guarantee quality and reliability. Cannabis seeds only original.","link":"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/","name":"Cannabis seeds","slug":"cannabis-seeds","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cannabis seeds-Nuka Seeds Bank<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cannabis seeds-Nuka Seeds Bank\" \/>\n<meta property=\"og:description\" content=\"Selling marijuana seeds. Here you can buy great original and medicinal marijuana seeds. We guarantee quality and reliability. Cannabis seeds only original.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuka Seeds Bank\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nukaseeds.cz\/wp-content\/uploads\/2021\/11\/nuka-seeds-logo-vector-neon-8-production.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2142\" \/>\n\t<meta property=\"og:image:height\" content=\"1457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seeds_nuka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/\",\"url\":\"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/\",\"name\":\"Cannabis seeds-Nuka Seeds Bank\",\"isPartOf\":{\"@id\":\"https:\/\/nukaseeds.cz\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nukaseeds.cz\/en\/growshop-nukaseeds-cz-cannabis-seeds\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cannabis seeds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nukaseeds.cz\/en\/#website\",\"url\":\"https:\/\/nukaseeds.cz\/en\/\",\"name\":\"Nuka Seeds Bank\",\"description\":\"Buy Cannabis Seeds, Buy Marijuana Seeds\",\"publisher\":{\"@id\":\"https:\/\/nukaseeds.cz\/en\/#organization\"},\"alternateName\":\"NukaSeeds cannabis seed bank\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nukaseeds.cz\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nukaseeds.cz\/en\/#organization\",\"name\":\"Nuka Trade s.r.o.\",\"url\":\"https:\/\/nukaseeds.cz\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nukaseeds.cz\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/nukaseeds.cz\/wp-content\/uploads\/2021\/11\/nuka-seeds-logo-vector-neon-8-production.png?fit=2142%2C1457&quality=70&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/nukaseeds.cz\/wp-content\/uploads\/2021\/11\/nuka-seeds-logo-vector-neon-8-production.png?fit=2142%2C1457&quality=70&ssl=1\",\"width\":2142,\"height\":1457,\"caption\":\"Nuka Trade s.r.o.\"},\"image\":{\"@id\":\"https:\/\/nukaseeds.cz\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Nukaseeds\/\",\"https:\/\/x.com\/seeds_nuka\",\"https:\/\/www.instagram.com\/nukaseeds\/\",\"https:\/\/www.youtube.com\/@nukaseeds1167\",\"https:\/\/www.tumblr.com\/nukaseeds\",\"https:\/\/www.linkedin.com\/company\/nukaseeds-ltd\/\",\"https:\/\/cz.pinterest.com\/Nukaseeds\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cannabis seeds-Nuka Seeds Bank","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/","og_locale":"en_US","og_type":"article","og_title":"Cannabis seeds-Nuka Seeds Bank","og_description":"Selling marijuana seeds. Here you can buy great original and medicinal marijuana seeds. We guarantee quality and reliability. Cannabis seeds only original.","og_url":"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/","og_site_name":"Nuka Seeds Bank","og_image":[{"width":2142,"height":1457,"url":"https:\/\/nukaseeds.cz\/wp-content\/uploads\/2021\/11\/nuka-seeds-logo-vector-neon-8-production.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@seeds_nuka","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/","url":"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/","name":"Cannabis seeds-Nuka Seeds Bank","isPartOf":{"@id":"https:\/\/nukaseeds.cz\/en\/#website"},"breadcrumb":{"@id":"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/nukaseeds.cz\/en\/buy-cannabis-seed\/cannabis-seeds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nukaseeds.cz\/en\/growshop-nukaseeds-cz-cannabis-seeds\/"},{"@type":"ListItem","position":2,"name":"Cannabis seeds"}]},{"@type":"WebSite","@id":"https:\/\/nukaseeds.cz\/en\/#website","url":"https:\/\/nukaseeds.cz\/en\/","name":"Nuka Seeds Bank","description":"Buy Cannabis Seeds, Buy Marijuana Seeds","publisher":{"@id":"https:\/\/nukaseeds.cz\/en\/#organization"},"alternateName":"NukaSeeds cannabis seed bank","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nukaseeds.cz\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nukaseeds.cz\/en\/#organization","name":"Nuka Trade s.r.o.","url":"https:\/\/nukaseeds.cz\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nukaseeds.cz\/en\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/nukaseeds.cz\/wp-content\/uploads\/2021\/11\/nuka-seeds-logo-vector-neon-8-production.png?fit=2142%2C1457&quality=70&ssl=1","contentUrl":"https:\/\/i0.wp.com\/nukaseeds.cz\/wp-content\/uploads\/2021\/11\/nuka-seeds-logo-vector-neon-8-production.png?fit=2142%2C1457&quality=70&ssl=1","width":2142,"height":1457,"caption":"Nuka Trade s.r.o."},"image":{"@id":"https:\/\/nukaseeds.cz\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nukaseeds\/","https:\/\/x.com\/seeds_nuka","https:\/\/www.instagram.com\/nukaseeds\/","https:\/\/www.youtube.com\/@nukaseeds1167","https:\/\/www.tumblr.com\/nukaseeds","https:\/\/www.linkedin.com\/company\/nukaseeds-ltd\/","https:\/\/cz.pinterest.com\/Nukaseeds\/"]}]}},"_links":{"self":[{"href":"https:\/\/nukaseeds.cz\/en\/wp-json\/wp\/v2\/product_cat\/7496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nukaseeds.cz\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/nukaseeds.cz\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/nukaseeds.cz\/en\/wp-json\/wp\/v2\/product?product_cat=7496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}